{"id":1014,"date":"2018-01-13T22:44:38","date_gmt":"2018-01-13T21:44:38","guid":{"rendered":"http:\/\/commentchangersavie.fr\/?p=1014"},"modified":"2018-09-06T07:47:10","modified_gmt":"2018-09-06T06:47:10","slug":"lachez-prise-avec","status":"publish","type":"post","link":"https:\/\/commentchangersavie.fr\/index.php\/2018\/01\/13\/lachez-prise-avec\/","title":{"rendered":"Lachez prise avec Soizick Fonteneau ( Sophrologue expert) et Sylvie Dorchies (Psycho-sociologue)"},"content":{"rendered":"<p>SOIZICK FONTENEAU ET SYLVIE DORCHIES<\/p>\n<p>Changer sa vie \u00e0 petits pas avec nos 2 Expertes!<\/p>\n<p>Pour une journ\u00e9e conviviale et l\u00e2chez prise en vous invitant \u00e0 une transformation. Sachez changer votre logiciel et envolez vous vers d&#8217;autres<strong>\u00a0&#8220;possibles&#8221;<\/strong>. Soizick Fonteneau ( Sophrologue expert) et Sylvie Dorchies (<\/p>\n<p><img loading=\"lazy\" class=\"size-full wp-image-1005\" src=\"http:\/\/commentchangersavie.fr\/wp-content\/uploads\/2018\/01\/hypnose_1514818857.jpg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/commentchangersavie.fr\/wp-content\/uploads\/2018\/01\/hypnose_1514818857.jpg 1280w, https:\/\/commentchangersavie.fr\/wp-content\/uploads\/2018\/01\/hypnose_1514818857-300x200.jpg 300w, https:\/\/commentchangersavie.fr\/wp-content\/uploads\/2018\/01\/hypnose_1514818857-768x512.jpg 768w, https:\/\/commentchangersavie.fr\/wp-content\/uploads\/2018\/01\/hypnose_1514818857-1024x682.jpg 1024w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>) vous entra\u00eeneront durant cette journ\u00e9e vers un v\u00e9ritable changement afin de pouvoir d\u00e9cider de vous engager vers des voies que vous aurez choisies.<\/p>\n<p>Pour cela 4 \u00e9tapes:<\/p>\n<ul>\n<li>Ouvrir<\/li>\n<li>D\u00e9cider<\/li>\n<li>Mobiliser<\/li>\n<li>Sentir<\/li>\n<\/ul>\n<p><img loading=\"lazy\" class=\"alignnone size-large wp-image-80328\" src=\"http:\/\/commentchangersavie.fr\/wp-content\/uploads\/2018\/01\/INFO-FB-ATELIER-SATYA-1024x733-3.jpg\" alt=\"\" width=\"1024\" height=\"733\" \/><\/p>\n<p>Ce &#8220;Stage&#8221; particulier, loin des sentiers battus, vous permettra de vous d\u00e9lester de nombres d&#8217;habitudes et pratiques afin de vous sentir plus l\u00e9ger, plus libre.<\/p>\n<p>RDV donc avec nos 2 expertes en changement de vie,\u00a0Soizick Fonteneau ( Sophrologue expert) et Sylvie Dorchies (Psycho-sociologue) le 11 F\u00e9vrier 2018 \u00e0 partir de 10h et jusqu&#8217;\u00e0 18h.<\/p>\n<p><a href=\"https:\/\/www.open-mag.net\/zen-2\/\"><img loading=\"lazy\" class=\" wp-image-80330\" src=\"http:\/\/commentchangersavie.fr\/wp-content\/uploads\/2018\/01\/zen_1515879206-1024x682-3.jpg\" alt=\"\" width=\"602\" height=\"401\" \/><\/a><\/p>\n<h2><span id=\"Une_forme_de_la_psychologie_sociale\" class=\"mw-headline\">La\u00a0sophrologie<\/span><\/h2>\n<p>La\u00a0<b>sophrologie<\/b>\u00a0est une approche de\u00a0<a title=\"D\u00e9veloppement personnel\" href=\"https:\/\/fr.wikipedia.org\/wiki\/D%C3%A9veloppement_personnel\">d\u00e9veloppement personnel<\/a><sup id=\"cite_ref-1\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-1\">1<\/a><\/sup><sup class=\"reference cite_virgule\">,<\/sup><sup id=\"cite_ref-2\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-2\">2<\/a><\/sup><sup class=\"reference cite_virgule\">,<\/sup><sup id=\"cite_ref-3\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-3\">3<\/a><\/sup>, qui s&#8217;int\u00e9resse \u00e0 l&#8217;<span title=\"Ce passage n\u00e9cessite une r\u00e9f\u00e9rence.\">\u00e9tude<\/span><sup class=\"need_ref_tag\" title=\"Ce passage n\u00e9cessite une r\u00e9f\u00e9rence.\"><a title=\"Aide:Pr\u00e9ciser un fait\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Aide:Pr%C3%A9ciser_un_fait\">[Comment\u00a0?]<\/a><\/sup>\u00a0de la conscience individuelle, dans une approche qui se veut\u00a0<span class=\"page_h\"><a class=\"mw-disambig\" title=\"Ph\u00e9nom\u00e9nologie\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Ph%C3%A9nom%C3%A9nologie\">ph\u00e9nom\u00e9nologique<\/a><\/span>\u00a0visant \u00e0 tenir compte de l&#8217;histoire personnelle de chacun<sup id=\"cite_ref-4\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-4\">4<\/a><\/sup>. Cette m\u00e9thode est parfois compar\u00e9e \u00e0 l&#8217;<a title=\"Hypnose\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Hypnose\">hypnose<\/a><sup id=\"cite_ref-Centre_d'information_et_de_pr\u00e9vention_sur_les_psychoth\u00e9rapies_abusives_et_d\u00e9viantes_5-0\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-Centre_d'information_et_de_pr%C3%A9vention_sur_les_psychoth%C3%A9rapies_abusives_et_d%C3%A9viantes-5\">5<\/a><\/sup>, qualifi\u00e9e parfois de\u00a0<a title=\"Psychoth\u00e9rapie\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Psychoth%C3%A9rapie\">psychoth\u00e9rapie<\/a><sup id=\"cite_ref-senon_6-0\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-senon-6\">6<\/a><\/sup><sup class=\"reference cite_virgule\">,<\/sup><sup id=\"cite_ref-7\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-7\">7<\/a><\/sup><sup class=\"reference cite_virgule\">,<\/sup><sup id=\"cite_ref-rapport_8-0\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-rapport-8\">8<\/a><\/sup><sup class=\"reference cite_virgule\">,<\/sup><sup id=\"cite_ref-9\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-9\">9<\/a><\/sup>, de\u00a0<a title=\"Techniques de relaxation\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Techniques_de_relaxation\">m\u00e9thode de relaxation<\/a><sup id=\"cite_ref-senon_6-1\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-senon-6\">6<\/a><\/sup><sup class=\"reference cite_virgule\">,<\/sup><sup id=\"cite_ref-servant_10-0\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-servant-10\">10<\/a><\/sup><sup class=\"reference cite_virgule\">,<\/sup><sup id=\"cite_ref-11\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-11\">11<\/a><\/sup><sup class=\"reference cite_virgule\">,<\/sup><sup id=\"cite_ref-12\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-12\">12<\/a><\/sup><sup class=\"reference cite_virgule\">,<\/sup><sup id=\"cite_ref-13\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-13\">13<\/a><\/sup>, voire de\u00a0<a class=\"mw-redirect\" title=\"M\u00e9decine alternative\" href=\"https:\/\/fr.wikipedia.org\/wiki\/M%C3%A9decine_alternative\">m\u00e9decine alternative<\/a><sup id=\"cite_ref-14\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-14\">14<\/a><\/sup>. De multiples \u00e9coles et pratiques ont \u00e9merg\u00e9 depuis la fondation en 1960 de la sophrologie par\u00a0<a title=\"Alfonso Caycedo\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Alfonso_Caycedo\">Alfonso Caycedo<\/a>, seule l\u2019appellation\u00a0<i><a title=\"Sophrologie cayc\u00e9dienne\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie_cayc%C3%A9dienne\">sophrologie cayc\u00e9dienne<\/a><\/i>\u00a0est prot\u00e9g\u00e9e par des droits, et reste li\u00e9e au fondateur de cette pratique.<\/p>\n<p>En France, la sophrologie a p\u00e9n\u00e9tr\u00e9 le secteur de la sant\u00e9, notamment le domaine des pathologies chroniques. Ainsi, il n\u2019est pas rare que des patients atteints de cancers\u00a0<span class=\"need_ref\" title=\"Ce passage devrait pr\u00e9ciser la personne ou l'organisation qui fait cette affirmation.\">se voient proposer<\/span><sup class=\"need_ref_tag\" title=\"Ce passage devrait pr\u00e9ciser la personne ou l'organisation qui fait cette affirmation.\"><a title=\"Aide:Par qui\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Aide:Par_qui\">[Par qui\u00a0?]<\/a><\/sup>, pendant ou apr\u00e8s des traitements de chimio- ou radioth\u00e9rapie, la pratique de la sophrologie comme \u00ab\u00a0soin de support\u00a0\u00bb. Elle est \u00e9galement utilis\u00e9e dans le sport et le monde de l\u2019entreprise<sup id=\"cite_ref-Centre_d'information_et_de_pr\u00e9vention_sur_les_psychoth\u00e9rapies_abusives_et_d\u00e9viantes_5-1\" class=\"reference\"><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie#cite_note-Centre_d'information_et_de_pr%C3%A9vention_sur_les_psychoth%C3%A9rapies_abusives_et_d%C3%A9viantes-5\">5<\/a><\/sup>.<\/p>\n<h2><span id=\"Une_forme_de_la_psychologie_sociale\" class=\"mw-headline\">La psychologie sociale<\/span><\/h2>\n<p>Pour les uns, la psychosociologie est la forme de\u00a0<a title=\"Psychologie sociale\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Psychologie_sociale\">psychologie sociale<\/a>\u00a0qui part de la psychologie de l&#8217;individu dans la soci\u00e9t\u00e9, de m\u00eame que la\u00a0<a class=\"mw-redirect\" title=\"Sociopsychologie\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Sociopsychologie\">sociopsychologie<\/a>\u00a0part des ph\u00e9nom\u00e8nes psychologiques proprement collectifs qui vont au-del\u00e0 des motivations individuelles.<\/p>\n<p>Pour les autres, elle se distingue de la psychologie sociale en ce sens qu&#8217;il s&#8217;agit d&#8217;un mode de traitement de l&#8217;individu essentiellement pratique.<\/p>\n<p>Il existe une approche d&#8217;intervention psychosociale int\u00e9ressante. En effet, \u00e0 l&#8217;Universit\u00e9 Laval, \u00e0 Qu\u00e9bec, Yvon P\u00e9pin a cr\u00e9\u00e9 cette approche visant \u00e0 analyser les probl\u00e8mes en fonction des interactions, de l&#8217;insertion, de l&#8217;intervention. (3I)<\/p>\n<p><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Sophrologie\" target=\"_blank\" rel=\"noopener noreferrer\">SOURCE WIKIPEDIA<\/a><\/p>\n<p><a href=\"https:\/\/www.open-mag.net\/zen\/\"><img loading=\"lazy\" class=\" wp-image-80329\" src=\"http:\/\/commentchangersavie.fr\/wp-content\/uploads\/2018\/01\/zen_1515879152-1024x809-3.jpg\" alt=\"\" width=\"561\" height=\"444\" \/><\/a><\/p>\n<p><a href=\"https:\/\/transformezvotrevie.wordpress.com\" target=\"_blank\" rel=\"noopener\">PARTENAIRE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SOIZICK FONTENEAU ET SYLVIE DORCHIES Changer sa vie \u00e0 petits pas avec nos 2 Expertes! Pour une journ\u00e9e conviviale et l\u00e2chez prise en vous invitant \u00e0 une transformation. Sachez changer votre logiciel et envolez vous vers d&#8217;autres\u00a0&#8220;possibles&#8221;. Soizick Fonteneau ( Sophrologue expert) et Sylvie Dorchies ( &nbsp; ) vous entra\u00eeneront durant cette journ\u00e9e vers un&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[14,37,17,39,154,10,6,23,27,16,212,209,211,210,25,8],"_links":{"self":[{"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1014"}],"collection":[{"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1014"}],"version-history":[{"count":3,"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1014\/revisions"}],"predecessor-version":[{"id":1672,"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/posts\/1014\/revisions\/1672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/media\/1035"}],"wp:attachment":[{"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/commentchangersavie.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}